{"id":3703,"date":"2022-11-10T14:00:46","date_gmt":"2022-11-10T14:00:46","guid":{"rendered":"http:\/\/cracpatrimoni.com\/faqs\/"},"modified":"2026-05-22T11:57:31","modified_gmt":"2026-05-22T11:57:31","slug":"faqs","status":"publish","type":"page","link":"https:\/\/cracpatrimoni.com\/es\/faqs\/","title":{"rendered":"FAQS"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"3703\" class=\"elementor elementor-3703 elementor-103\" data-elementor-post-type=\"page\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-3e080e3b elementor-section-height-min-height elementor-section-items-stretch elementor-hidden-tablet elementor-hidden-mobile elementor-section-boxed elementor-section-height-default\" data-id=\"3e080e3b\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-1e60d03e\" data-id=\"1e60d03e\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4d67e495 elementor-hidden-tablet elementor-hidden-mobile elementor-widget elementor-widget-global elementor-global-5969 elementor-global-5955 elementor-widget-image\" data-id=\"4d67e495\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/cracpatrimoni.com\/es\/directorio-profesionales\/\">\n\t\t\t\t\t\t\t<img decoding=\"async\" width=\"17\" height=\"322\" src=\"https:\/\/cracpatrimoni.com\/wp-content\/uploads\/2023\/01\/DIRECTORIO.png\" class=\"attachment-large size-large wp-image-5954\" alt=\"\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-284b948 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"284b948\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-04d5dc1\" data-id=\"04d5dc1\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-16afc0c elementor-widget elementor-widget-heading\" data-id=\"16afc0c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">FAQS<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-81db804 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"81db804\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-461cc7fa\" data-id=\"461cc7fa\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-2574dec8 elementor-section-content-space-around seccionIzq elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"2574dec8\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-203cacd3\" data-id=\"203cacd3\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-780aad92 btn-muestra-conservador btn-faq elementor-align-justify elementor-mobile-align-justify elementor-widget elementor-widget-button\" data-id=\"780aad92\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"#\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-icon\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-chevron-down\"><\/i>\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">\u00bfQu\u00e9 es un Conservador-Restaurador?<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-23886bae btn-oculta-conservador btn-faq elementor-align-justify elementor-widget elementor-widget-button\" data-id=\"23886bae\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"#\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-icon\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-chevron-up\"><\/i>\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">\u00bfQu\u00e9 es un Conservador-Restaurador?<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-75bf4688 contingut-conservador elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"75bf4688\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-4450863f\" data-id=\"4450863f\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-afdd1b7 elementor-section-content-space-around seccionIzq elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"afdd1b7\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-8d7d7d2\" data-id=\"8d7d7d2\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-ed689d9 elementor-widget elementor-widget-text-editor\" data-id=\"ed689d9\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>El <strong>conservador-restaurador<\/strong> se dedica a salvaguardar la parte &#8220;f\u00edsica&#8221; de los bienes culturales. \u00c9s aquel profesional que tiene la formaci\u00f3n, el conocimiento, la habilidad, la experiencia y la comprensi\u00f3n necesarias para actuar con el objetivo de preservar el patrimonio cultural en beneficio de las generaciones presentes y futuras, contribuyendo a la percepci\u00f3n, apreciaci\u00f3n y comprensi\u00f3n del patrimonio, respetando su contexto ambiental, su significado y sus propiedades f\u00edsicas, y que lo hace siguiendo un c\u00f3digo \u00e9tico como el suscrito por la <a href=\"https:\/\/www.ecco-eu.org\/\" target=\"_blank\" rel=\"noopener\">Confederaci\u00f3 E.C.C.O.<\/a> (European Confederation of Conservator-Restorers\u2019 Organisations) des del 1993. (\u201cE.C.C.O., Code of Ethics, 1993\u201d).<\/p><p>Sus actividades incluyen: el examen y el estudio tecnol\u00f3gico, la documentaci\u00f3n, la conservaci\u00f3n preventiva y los tratamientos de conservaci\u00f3n-restauraci\u00f3n de los bienes culturales. Algunos profesionales trabajan en instituciones, pero la mayor\u00eda de los conservadores-restauradores son aut\u00f3nomos y tienen, por lo general, una o dos especializaciones. Pueden asociarse entre ellos para ofrecer servicios completos a nivel de materiales o \u00e9poca hist\u00f3rica.<\/p><p>Tambi\u00e9n es <strong>competencia del Conservador-Restaurador<\/strong>:<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-8fded03 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"8fded03\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-inner-column elementor-element elementor-element-f930529\" data-id=\"f930529\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-d953576 elementor-widget elementor-widget-text-editor\" data-id=\"d953576\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Desarrollar <strong>programas<\/strong> de conservaci\u00f3n-restauraci\u00f3n o supervisi\u00f3n.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-inner-column elementor-element elementor-element-c446613\" data-id=\"c446613\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-a4fa9c0 elementor-widget elementor-widget-text-editor\" data-id=\"a4fa9c0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Dar <strong>consejo<\/strong> y <strong>asistencia<\/strong> t\u00e9cnica para la conservaci\u00f3n-restauraci\u00f3n del patrimonio cultural.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-inner-column elementor-element elementor-element-c7b9c95\" data-id=\"c7b9c95\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-d4d772a elementor-widget elementor-widget-text-editor\" data-id=\"d4d772a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Preparar <strong>informes t\u00e9cnicos<\/strong> sobre el patrimonio cultural, excluyendo cualquier juicio sobre su valor de mercado.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-inner-column elementor-element elementor-element-4f6e325\" data-id=\"4f6e325\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3db2a1f elementor-widget elementor-widget-text-editor\" data-id=\"3db2a1f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Realizar <strong>investigaci\u00f3n<\/strong> en el campo de la conservaci\u00f3n-restauraci\u00f3n.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-5cb8600 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"5cb8600\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-inner-column elementor-element elementor-element-215c824\" data-id=\"215c824\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2e16aa2 elementor-widget elementor-widget-text-editor\" data-id=\"2e16aa2\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Promocionar un mayor <strong>conocimiento<\/strong> de lo que es la conservaci\u00f3n-restauraci\u00f3n.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-inner-column elementor-element elementor-element-a45b59e\" data-id=\"a45b59e\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-6b2f11c elementor-widget elementor-widget-text-editor\" data-id=\"6b2f11c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Desarrollar <strong>programas<\/strong> <strong>educativos<\/strong> e impartir docencia sobre conservaci\u00f3n-restauraci\u00f3n.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-inner-column elementor-element elementor-element-ef30564\" data-id=\"ef30564\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-9eab3c3 elementor-widget elementor-widget-text-editor\" data-id=\"9eab3c3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><strong>Disseminar<\/strong> la informaci\u00f3 obtinguda de l\u2019ex\u00e0men, <br\/>el tractament o la recerca.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-inner-column elementor-element elementor-element-24cf92a elementor-hidden-mobile\" data-id=\"24cf92a\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<div class=\"elementor-element elementor-element-c4474bb elementor-widget elementor-widget-text-editor\" data-id=\"c4474bb\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><strong>Directrius professionals E.C.C.O<\/strong><\/p><p>Descarrega el PDF:\u00a0<br \/><a href=\"https:\/\/cracpatrimoni.com\/ecco_directrius-professionals-2\/\" rel=\"attachment wp-att-8301\">ECCO_directrius professionals<\/a><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-3b26eb7 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"3b26eb7\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-788182c\" data-id=\"788182c\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-ce6750b elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"ce6750b\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-dd72ac7\" data-id=\"dd72ac7\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-4b5790b elementor-section-content-space-around seccionIzq elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"4b5790b\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-bd091c5\" data-id=\"bd091c5\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-309d638 btn-muestra-estudiar btn-faq elementor-align-justify elementor-widget elementor-widget-button\" data-id=\"309d638\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"#\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-icon\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-chevron-down\"><\/i>\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">\u00bfD\u00f3nde estudiar conservaci\u00f3n-restauraci\u00f3n en Catalu\u00f1a?<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7af52de btn-oculta-estudiar btn-faq elementor-align-justify elementor-widget elementor-widget-button\" data-id=\"7af52de\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"#\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-icon\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-chevron-up\"><\/i>\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">\u00bfD\u00f3nde estudiar conservaci\u00f3n-restauraci\u00f3n en Catalu\u00f1a?<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-d4c743f contingut-estudiar elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"d4c743f\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-42cabf1\" data-id=\"42cabf1\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-52b5e38 elementor-section-content-space-around seccionIzq elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"52b5e38\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-efb32bf\" data-id=\"efb32bf\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-35122b1 elementor-widget elementor-widget-text-editor\" data-id=\"35122b1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Actualmente en Catalu\u00f1a existen dos centros donde se pueden cursar los estudios oficiales de conservaci\u00f3n-restauraci\u00f3n:<br><br><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-b15746d elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"b15746d\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-extended\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-70bfe3e\" data-id=\"70bfe3e\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-7c68eb7 elementor-widget elementor-widget-text-editor\" data-id=\"7c68eb7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><strong>Facultad de Bellas Artes de la Universidad de Barcelona (UB)<\/strong><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a46c990 elementor-widget elementor-widget-image\" data-id=\"a46c990\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.ub.edu\/portal\/web\/bellesarts\" target=\"_blank\" rel=\"nofollow\">\n\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"533\" height=\"286\" src=\"https:\/\/cracpatrimoni.com\/wp-content\/uploads\/2022\/12\/Facultat-de-Belles-Arts-de-la-Universitat-de-Barcelona-UB.png\" class=\"attachment-full size-full wp-image-3379\" alt=\"\" srcset=\"https:\/\/cracpatrimoni.com\/wp-content\/uploads\/2022\/12\/Facultat-de-Belles-Arts-de-la-Universitat-de-Barcelona-UB.png 533w, https:\/\/cracpatrimoni.com\/wp-content\/uploads\/2022\/12\/Facultat-de-Belles-Arts-de-la-Universitat-de-Barcelona-UB-300x161.png 300w, https:\/\/cracpatrimoni.com\/wp-content\/uploads\/2022\/12\/Facultat-de-Belles-Arts-de-la-Universitat-de-Barcelona-UB-500x268.png 500w\" sizes=\"(max-width: 533px) 100vw, 533px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-680b5af elementor-widget elementor-widget-text-editor\" data-id=\"680b5af\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Actualmente ofrece el Grado en Conservaci\u00f3n Restauraci\u00f3n de Bienes Culturales y un M\u00e1ster oficial en Conservaci\u00f3n-Restauraci\u00f3n que permite continuar con el doctorado en la especialidad de Conservaci\u00f3n-Restauraci\u00f3n.<br\/><br\/>Tambi\u00e9n imparten el M\u00e1ster Universitario en Tratamientos de Limpieza para Bienes Culturales.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-d3bbfea\" data-id=\"d3bbfea\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-beb1490 elementor-widget elementor-widget-text-editor\" data-id=\"beb1490\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><strong>Escuela Superior de Conservaci\u00f3n Restauraci\u00f3n de Bienes Culturales de Catalu\u00f1a (ESCRBCC)<\/strong><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1bdb43b elementor-widget elementor-widget-image\" data-id=\"1bdb43b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.escrbcc.cat\/es\/\" target=\"_blank\" rel=\"nofollow\">\n\t\t\t\t\t\t\t<img decoding=\"async\" width=\"540\" height=\"286\" src=\"https:\/\/cracpatrimoni.com\/wp-content\/uploads\/2022\/12\/ESCRBCC.png\" class=\"attachment-full size-full wp-image-3378\" alt=\"\" srcset=\"https:\/\/cracpatrimoni.com\/wp-content\/uploads\/2022\/12\/ESCRBCC.png 540w, https:\/\/cracpatrimoni.com\/wp-content\/uploads\/2022\/12\/ESCRBCC-300x159.png 300w, https:\/\/cracpatrimoni.com\/wp-content\/uploads\/2022\/12\/ESCRBCC-500x265.png 500w\" sizes=\"(max-width: 540px) 100vw, 540px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2781c98 elementor-widget elementor-widget-text-editor\" data-id=\"2781c98\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Actualmente, ofrece el Grado en Ense\u00f1anzas Art\u00edsticas Superiores de Conservaci\u00f3n y Restauraci\u00f3n de Bienes Culturales, que queda incluido a todos los efectos en el nivel 2 del Marco Espa\u00f1ol de Cualificaciones para la Educaci\u00f3n Superior y ser\u00e1 equivalente al t\u00edtulo universitario de Grado.<\/p><p>Tambi\u00e9n imparte el M\u00e1ster en ense\u00f1anzas art\u00edsticas de Conservaci\u00f3n y Restauraci\u00f3n de Patrimonio Fotogr\u00e1fico y el M\u00e1ster Oficial en Conservaci\u00f3n Preventiva de Bienes Culturales Muebles e Inmuebles.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>FAQS \u00bfQu\u00e9 es un Conservador-Restaurador? \u00bfQu\u00e9 es un Conservador-Restaurador? El conservador-restaurador se dedica a salvaguardar la parte &#8220;f\u00edsica&#8221; de los bienes culturales. \u00c9s aquel profesional que tiene la formaci\u00f3n, el conocimiento, la habilidad, la experiencia y la comprensi\u00f3n necesarias para actuar con el objetivo de preservar el patrimonio cultural en beneficio de las generaciones presentes [&hellip;]<\/p>\n","protected":false},"author":29,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"elementor_header_footer","meta":{"_acf_changed":false,"footnotes":""},"class_list":["post-3703","page","type-page","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>FAQS - CRAC<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/cracpatrimoni.com\/es\/faqs\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"FAQS - CRAC\" \/>\n<meta property=\"og:description\" content=\"FAQS \u00bfQu\u00e9 es un Conservador-Restaurador? \u00bfQu\u00e9 es un Conservador-Restaurador? El conservador-restaurador se dedica a salvaguardar la parte &#8220;f\u00edsica&#8221; de los bienes culturales. \u00c9s aquel profesional que tiene la formaci\u00f3n, el conocimiento, la habilidad, la experiencia y la comprensi\u00f3n necesarias para actuar con el objetivo de preservar el patrimonio cultural en beneficio de las generaciones presentes [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/cracpatrimoni.com\/es\/faqs\/\" \/>\n<meta property=\"og:site_name\" content=\"CRAC\" \/>\n<meta property=\"article:modified_time\" content=\"2026-05-22T11:57:31+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/cracpatrimoni.com\/wp-content\/uploads\/2023\/01\/DIRECTORI.png\" \/>\n\t<meta property=\"og:image:width\" content=\"17\" \/>\n\t<meta property=\"og:image:height\" content=\"308\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/cracpatrimoni.com\\\/es\\\/faqs\\\/\",\"url\":\"https:\\\/\\\/cracpatrimoni.com\\\/es\\\/faqs\\\/\",\"name\":\"FAQS - CRAC\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/cracpatrimoni.com\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/cracpatrimoni.com\\\/es\\\/faqs\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/cracpatrimoni.com\\\/es\\\/faqs\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/cracpatrimoni.com\\\/wp-content\\\/uploads\\\/2023\\\/01\\\/DIRECTORI.png\",\"datePublished\":\"2022-11-10T14:00:46+00:00\",\"dateModified\":\"2026-05-22T11:57:31+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/cracpatrimoni.com\\\/es\\\/faqs\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/cracpatrimoni.com\\\/es\\\/faqs\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/cracpatrimoni.com\\\/es\\\/faqs\\\/#primaryimage\",\"url\":\"https:\\\/\\\/cracpatrimoni.com\\\/wp-content\\\/uploads\\\/2023\\\/01\\\/DIRECTORI.png\",\"contentUrl\":\"https:\\\/\\\/cracpatrimoni.com\\\/wp-content\\\/uploads\\\/2023\\\/01\\\/DIRECTORI.png\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/cracpatrimoni.com\\\/es\\\/faqs\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/cracpatrimoni.com\\\/es\\\/inicio\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"FAQS\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/cracpatrimoni.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/cracpatrimoni.com\\\/es\\\/\",\"name\":\"CRAC\",\"description\":\"Conservadors restauradors associats de Catalunya\",\"publisher\":{\"@id\":\"https:\\\/\\\/cracpatrimoni.com\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/cracpatrimoni.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/cracpatrimoni.com\\\/es\\\/#organization\",\"name\":\"CRAC\",\"url\":\"https:\\\/\\\/cracpatrimoni.com\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/cracpatrimoni.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/cracpatrimoni.com\\\/wp-content\\\/uploads\\\/2022\\\/11\\\/logocrac-1-1.png\",\"contentUrl\":\"https:\\\/\\\/cracpatrimoni.com\\\/wp-content\\\/uploads\\\/2022\\\/11\\\/logocrac-1-1.png\",\"width\":384,\"height\":152,\"caption\":\"CRAC\"},\"image\":{\"@id\":\"https:\\\/\\\/cracpatrimoni.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"FAQS - CRAC","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/cracpatrimoni.com\/es\/faqs\/","og_locale":"es_ES","og_type":"article","og_title":"FAQS - CRAC","og_description":"FAQS \u00bfQu\u00e9 es un Conservador-Restaurador? \u00bfQu\u00e9 es un Conservador-Restaurador? El conservador-restaurador se dedica a salvaguardar la parte &#8220;f\u00edsica&#8221; de los bienes culturales. \u00c9s aquel profesional que tiene la formaci\u00f3n, el conocimiento, la habilidad, la experiencia y la comprensi\u00f3n necesarias para actuar con el objetivo de preservar el patrimonio cultural en beneficio de las generaciones presentes [&hellip;]","og_url":"https:\/\/cracpatrimoni.com\/es\/faqs\/","og_site_name":"CRAC","article_modified_time":"2026-05-22T11:57:31+00:00","og_image":[{"width":17,"height":308,"url":"https:\/\/cracpatrimoni.com\/wp-content\/uploads\/2023\/01\/DIRECTORI.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_misc":{"Tiempo de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/cracpatrimoni.com\/es\/faqs\/","url":"https:\/\/cracpatrimoni.com\/es\/faqs\/","name":"FAQS - CRAC","isPartOf":{"@id":"https:\/\/cracpatrimoni.com\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/cracpatrimoni.com\/es\/faqs\/#primaryimage"},"image":{"@id":"https:\/\/cracpatrimoni.com\/es\/faqs\/#primaryimage"},"thumbnailUrl":"https:\/\/cracpatrimoni.com\/wp-content\/uploads\/2023\/01\/DIRECTORI.png","datePublished":"2022-11-10T14:00:46+00:00","dateModified":"2026-05-22T11:57:31+00:00","breadcrumb":{"@id":"https:\/\/cracpatrimoni.com\/es\/faqs\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/cracpatrimoni.com\/es\/faqs\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/cracpatrimoni.com\/es\/faqs\/#primaryimage","url":"https:\/\/cracpatrimoni.com\/wp-content\/uploads\/2023\/01\/DIRECTORI.png","contentUrl":"https:\/\/cracpatrimoni.com\/wp-content\/uploads\/2023\/01\/DIRECTORI.png"},{"@type":"BreadcrumbList","@id":"https:\/\/cracpatrimoni.com\/es\/faqs\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/cracpatrimoni.com\/es\/inicio\/"},{"@type":"ListItem","position":2,"name":"FAQS"}]},{"@type":"WebSite","@id":"https:\/\/cracpatrimoni.com\/es\/#website","url":"https:\/\/cracpatrimoni.com\/es\/","name":"CRAC","description":"Conservadors restauradors associats de Catalunya","publisher":{"@id":"https:\/\/cracpatrimoni.com\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/cracpatrimoni.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/cracpatrimoni.com\/es\/#organization","name":"CRAC","url":"https:\/\/cracpatrimoni.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/cracpatrimoni.com\/es\/#\/schema\/logo\/image\/","url":"https:\/\/cracpatrimoni.com\/wp-content\/uploads\/2022\/11\/logocrac-1-1.png","contentUrl":"https:\/\/cracpatrimoni.com\/wp-content\/uploads\/2022\/11\/logocrac-1-1.png","width":384,"height":152,"caption":"CRAC"},"image":{"@id":"https:\/\/cracpatrimoni.com\/es\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/cracpatrimoni.com\/es\/wp-json\/wp\/v2\/pages\/3703","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cracpatrimoni.com\/es\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/cracpatrimoni.com\/es\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/cracpatrimoni.com\/es\/wp-json\/wp\/v2\/users\/29"}],"replies":[{"embeddable":true,"href":"https:\/\/cracpatrimoni.com\/es\/wp-json\/wp\/v2\/comments?post=3703"}],"version-history":[{"count":24,"href":"https:\/\/cracpatrimoni.com\/es\/wp-json\/wp\/v2\/pages\/3703\/revisions"}],"predecessor-version":[{"id":9031,"href":"https:\/\/cracpatrimoni.com\/es\/wp-json\/wp\/v2\/pages\/3703\/revisions\/9031"}],"wp:attachment":[{"href":"https:\/\/cracpatrimoni.com\/es\/wp-json\/wp\/v2\/media?parent=3703"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}